{"id":15574,"date":"2022-01-06T12:46:13","date_gmt":"2022-01-06T17:46:13","guid":{"rendered":"https:\/\/chillepoxy.com\/default-fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/"},"modified":"2023-03-07T13:55:29","modified_gmt":"2023-03-07T18:55:29","slug":"taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits","status":"publish","type":"post","link":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/","title":{"rendered":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions"},"content":{"rendered":"<h1 style=\"text-align: left;\">R\u00e9sine \u00e9poxy molle et collante : causes et solutions<\/h1>\n<p>La r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9, une humidit\u00e9 \u00e9lev\u00e9e et des temp\u00e9ratures \u00e9lev\u00e9es. Une fois le temps de durcissement pass\u00e9, si vous constatez que votre r\u00e9sine reste collante, il est tr\u00e8s probable que vous n&rsquo;ayez pas suivi strictement le ratio ou le processus de m\u00e9lange indiqu\u00e9.<\/p>\n<p>Une solution possible consiste \u00e0 s&rsquo;assurer que la r\u00e9sine et le durcisseur sont bien m\u00e9lang\u00e9s et dans le bon rapport. Un mauvais m\u00e9lange peut entra\u00eener un durcissement incorrect de l&rsquo;\u00e9poxyde, ce qui donne un fini mou ou collant.<\/p>\n<p>Un autre probl\u00e8me potentiel est une humidit\u00e9 \u00e9lev\u00e9e ou des temp\u00e9ratures \u00e9lev\u00e9es. La r\u00e9sine \u00e9poxy pr\u00e9f\u00e8re une temp\u00e9rature comprise entre 68 et 74 \u00b0 F et une humidit\u00e9 inf\u00e9rieure \u00e0 60 %. Si vous versez de la r\u00e9sine \u00e9poxy avec un taux d&rsquo;humidit\u00e9 \u00e9lev\u00e9, cela peut affecter le processus de durcissement et entra\u00eener un certain nombre de probl\u00e8mes. Un autre probl\u00e8me qui peut survenir lors de la coul\u00e9e d&rsquo;\u00e9poxy avec une humidit\u00e9 \u00e9lev\u00e9e est le d\u00e9veloppement d&rsquo;une surface trouble ou d&rsquo;un r\u00e9sidu blanc et poudreux appel\u00e9 \u00ab\u00a0blush\u00a0\u00bb. Le blush est caus\u00e9 par l&rsquo;humidit\u00e9 emprisonn\u00e9e dans l&rsquo;\u00e9poxy pendant le processus de durcissement. Cela peut rendre la surface de l&rsquo;\u00e9poxy terne et trouble.<\/p>\n<p>Pour \u00e9viter ces probl\u00e8mes, il est recommand\u00e9 de verser l&rsquo;\u00e9poxy dans une pi\u00e8ce ou un espace avec un taux d&rsquo;humidit\u00e9 inf\u00e9rieur \u00e0 60 % et une temp\u00e9rature comprise entre 60 et 90 \u00b0F. Si le niveau d&rsquo;humidit\u00e9 est \u00e9lev\u00e9 dans votre r\u00e9gion, vous voudrez peut-\u00eatre envisager d&rsquo;utiliser un d\u00e9shumidificateur ou d&rsquo;attendre une journ\u00e9e avec une humidit\u00e9 plus faible pour verser votre \u00e9poxy.<\/p>\n<p>Si l&rsquo;\u00e9poxy a d\u00e9j\u00e0 \u00e9t\u00e9 coul\u00e9 et a mal durci, il peut \u00eatre n\u00e9cessaire de le poncer ou de le recouvrir d&rsquo;une nouvelle couche d&rsquo;\u00e9poxy. Cependant, il est important de s&rsquo;assurer que la cause sous-jacente du probl\u00e8me a \u00e9t\u00e9 r\u00e9solue avant d&rsquo;appliquer une nouvelle couche.<\/p>\n<p>Il est \u00e9galement important de noter que certaines r\u00e9sines \u00e9poxy sont con\u00e7ues pour \u00eatre souples ou flexibles, il est donc important d&rsquo;utiliser le bon type de r\u00e9sine pour votre projet. Si vous n&rsquo;\u00eates pas s\u00fbr du type d&rsquo;\u00e9poxy \u00e0 utiliser, il est pr\u00e9f\u00e9rable de consulter le fabricant ou un professionnel pour obtenir des conseils.<\/p>\n<p>Si tout le reste \u00e9choue, vous devrez peut-\u00eatre consulter un professionnel ou le fabricant pour obtenir des conseils suppl\u00e9mentaires sur la fa\u00e7on de d\u00e9panner et de r\u00e9soudre le probl\u00e8me.<\/p>\n<h3 style=\"text-align: left;\">Si le produit n&rsquo;a pas atteint sa duret\u00e9 totale, pr\u00e9sente des points faibles ou ne durcit pas correctement, cela peut \u00eatre d\u00fb \u00e0 plusieurs facteurs :<\/h3>\n<ul>\n<li>Ratio non pr\u00e9cis (poids ou volume)<\/li>\n<li>Le processus de m\u00e9lange n&rsquo;est pas effectu\u00e9 correctement, ce qui fait que les mol\u00e9cules ne sont pas homog\u00e8nes \u00e0 100%, de sorte que la cha\u00eene mol\u00e9culaire n&rsquo;est pas compl\u00e8tement ferm\u00e9e, ce qui entra\u00eene moins de SHORE D (duret\u00e9), moins de r\u00e9sistance \u00e0 la chaleur et des points faibles.<\/li>\n<li>M\u00e9langer la r\u00e9sine pendant un minimum du temps recommand\u00e9 est imp\u00e9ratif<\/li>\n<li>Les c\u00f4t\u00e9s et le fond du gobelet de m\u00e9lange plat doivent \u00eatre gratt\u00e9s r\u00e9guli\u00e8rement pour \u00e9liminer l&rsquo;\u00e9poxyde non m\u00e9lang\u00e9.<\/li>\n<li>Utilisez des outils professionnels pour m\u00e9langer votre r\u00e9sine, comme une spatule plate en m\u00e9tal et des m\u00e9langeurs rapides. \u00c9vitez les cuill\u00e8res, les fourchettes, les b\u00e2tons de popsicle, les goujons 2 x 4, les balais ; nous avons tout vu\u2026 croyez-moi !<\/li>\n<li>Temp\u00e9rature : chaque F\/C sous 72F\/22C ralentira le processus de durcissement de 15 \u00e0 25 % selon la masse.<\/li>\n<li>Avez-vous utilis\u00e9 la partie B appropri\u00e9e pour la partie A appropri\u00e9e ?<\/li>\n<li>N&rsquo;utilisez pas les pi\u00e8ces A et B de syst\u00e8mes diff\u00e9rents, la stoechiom\u00e9trie changera et la r\u00e9sine ne durcira pas.<\/li>\n<li>N&rsquo;utilisez pas d&rsquo;outils sales ou\/et de seaux sales car ils peuvent contaminer votre r\u00e9sine et causer des probl\u00e8mes.<\/li>\n<li>Ne m\u00e9langez pas de petites quantit\u00e9s telles que quelques millilitres ou grammes des produits <a href=\"https:\/\/chillepoxy.com\/fr\/\">CHILL EPOXY\u2122<\/a> car un petit pourcentage d&rsquo;erreur sur la masse\/volume de r\u00e9sine repr\u00e9sentera une grande diff\u00e9rence de pourcentage sur le rapport volume\/poids et cela pourrait affecter le durcissement de la r\u00e9sine.<\/li>\n<\/ul>\n<p>Une erreur de 3 millilitres sur 30 millilitres \u00e9quivaut \u00e0 10 % et cela affectera grandement le processus de durcissement. Une erreur de 3 millilitres sur 300 millilitres \u00e9quivaut \u00e0 1%, ce qui est tout \u00e0 fait acceptable.<\/p>\n<p>Assurez-vous de suivre ces recommandations pour r\u00e9ussir votre projet et \u00e9viter les pertes de r\u00e9sine, les pertes de temps et les frustrations. Pr\u00e8s de 100 % des probl\u00e8mes proviennent d&rsquo;une mauvaise pes\u00e9e, mesure et m\u00e9lange.<\/p>\n<h2>Solution pour r\u00e9cup\u00e9rer l&rsquo;\u00e9poxyde non durci, mou ou collant<\/h2>\n<p>Si vous avez de l&rsquo;\u00e9poxy non durci, mou ou collant, il existe quelques solutions qui peuvent aider \u00e0 sauver le projet.<\/p>\n<p>Une solution consiste \u00e0 recouvrir l&rsquo;\u00e9poxy d&rsquo;une nouvelle couche, apr\u00e8s avoir ponc\u00e9 la surface existante pour \u00e9liminer les imperfections, puis \u00e0 appliquer une nouvelle couche d&rsquo;\u00e9poxy. Il est important de s&rsquo;assurer que la cause sous-jacente du probl\u00e8me a \u00e9t\u00e9 r\u00e9solue avant d&rsquo;appliquer une nouvelle couche, comme un bon m\u00e9lange de la r\u00e9sine et du durcisseur, et une temp\u00e9rature et un niveau d&rsquo;humidit\u00e9 corrects.<\/p>\n<p>Une autre solution consiste \u00e0 utiliser une source de chaleur ou un pistolet thermique pour essayer d&rsquo;acc\u00e9l\u00e9rer le processus de durcissement. Cela peut \u00eatre fait en exposant l&rsquo;\u00e9poxy \u00e0 la chaleur pour activer la mol\u00e9cule et gagner en duret\u00e9. Cependant, il est important d&rsquo;\u00eatre prudent lors de l&rsquo;utilisation de cette m\u00e9thode car trop de chaleur peut faire jaunir l&rsquo;\u00e9poxy, le ramollir ou le d\u00e9colorer, vous devez donc utiliser une temp\u00e9rature et une dur\u00e9e mod\u00e9r\u00e9es. De plus, cette technique peut ne pas \u00eatre utilis\u00e9e si l&rsquo;\u00e9poxy est tr\u00e8s collant.<\/p>\n<p>Une troisi\u00e8me solution consiste \u00e0 utiliser notre <a href=\"https:\/\/chillepoxy.com\/product\/eco-frendly-epoxy-resin-cleaner-remover\/\">SOLUTION DE NETTOYAGE DE R\u00c9SINE \u00c9COLOGIQUE<\/a> pour \u00e9liminer les taches collantes. Cela peut \u00eatre fait en brossant ou en roulant le nettoyant pour r\u00e9sine sur la surface de l&rsquo;\u00e9poxy, puis en enlevant l&rsquo;\u00e9poxy avec une raclette ou un grattoir en m\u00e9tal.<\/p>\n<p>Si les solutions ci-dessus ne fonctionnent pas, il peut \u00eatre pr\u00e9f\u00e9rable de consulter l&rsquo;\u00e9quipe technique de <a href=\"mailto:support@polymerestechnologies.com\">Polymeres Technologies<\/a> pour obtenir des conseils suppl\u00e9mentaires sur la fa\u00e7on de d\u00e9panner et de r\u00e9soudre le probl\u00e8me.<\/p>\n<p>De plus, il est important de se rappeler que le durcissement de l&rsquo;\u00e9poxyde est un processus complexe qui peut \u00eatre affect\u00e9 par de nombreux facteurs tels que la temp\u00e9rature, l&rsquo;humidit\u00e9, les rapports de m\u00e9lange et d&rsquo;autres facteurs environnementaux, il est donc toujours recommand\u00e9 de suivre les instructions et les directives du fabricant pour obtenir le meilleur r\u00e9sultats.<\/p>\n<h3>La science derri\u00e8re la r\u00e9sine \u00e9poxy de haute qualit\u00e9<\/h3>\n<p>Chez Polymeres Technologies Inc, nous sommes fiers de produire une r\u00e9sine \u00e9poxy de haute qualit\u00e9 qui r\u00e9pond aux normes les plus \u00e9lev\u00e9es de l&rsquo;industrie. Notre processus de contr\u00f4le de qualit\u00e9 strict garantit que chaque lot de r\u00e9sine \u00e9poxy est test\u00e9 pour sa coh\u00e9rence et ses performances, de sorte que vous pouvez \u00eatre s\u00fbr que vous obtenez un produit qui fournira les meilleurs r\u00e9sultats.<\/p>\n<p>Notre processus de contr\u00f4le qualit\u00e9 commence par l&rsquo;approvisionnement uniquement en mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9 pour notre r\u00e9sine \u00e9poxy. Nos fournisseurs sont soigneusement s\u00e9lectionn\u00e9s pour s&rsquo;assurer qu&rsquo;ils r\u00e9pondent \u00e0 nos normes de qualit\u00e9 strictes. Une fois les mati\u00e8res premi\u00e8res re\u00e7ues, elles sont soigneusement inspect\u00e9es et test\u00e9es pour s&rsquo;assurer qu&rsquo;elles r\u00e9pondent \u00e0 nos sp\u00e9cifications.<\/p>\n<p>Une fois les mati\u00e8res premi\u00e8res approuv\u00e9es, nos chimistes exp\u00e9riment\u00e9s m\u00e9langent et mesurent soigneusement la r\u00e9sine et le durcisseur dans des proportions pr\u00e9cises pour garantir un produit homog\u00e8ne. Notre r\u00e9sine \u00e9poxy est ensuite coul\u00e9e dans des moules, o\u00f9 elle est durcie et inspect\u00e9e pour tout d\u00e9faut. La derni\u00e8re \u00e9tape de notre processus de contr\u00f4le de la qualit\u00e9 consiste en des tests rigoureux. Notre r\u00e9sine \u00e9poxy est test\u00e9e pour sa solidit\u00e9, sa flexibilit\u00e9 et sa r\u00e9sistance \u00e0 la chaleur, aux produits chimiques et \u00e0 d&rsquo;autres facteurs environnementaux. Ce n&rsquo;est qu&rsquo;apr\u00e8s avoir pass\u00e9 tous ces tests que la r\u00e9sine \u00e9poxy est approuv\u00e9e pour la distribution.<\/p>\n<p>Nous comprenons que parfois, malgr\u00e9 tous nos efforts, nos clients peuvent rencontrer des probl\u00e8mes avec notre r\u00e9sine \u00e9poxy. Cependant, nous voulons nous assurer que la plupart des mauvais r\u00e9sultats sont caus\u00e9s par les utilisateurs finaux, tels qu&rsquo;un m\u00e9lange incorrect, une humidit\u00e9 \u00e9lev\u00e9e ou des temp\u00e9ratures \u00e9lev\u00e9es qui affectent le processus de durcissement et provoquent un durcissement incorrect de l&rsquo;\u00e9poxy.<\/p>\n<p>Nous recommandons toujours \u00e0 nos clients de lire attentivement et de suivre les instructions et les directives du fabricant pour obtenir les meilleurs r\u00e9sultats. Et en cas de probl\u00e8me, nous sommes toujours disponibles pour r\u00e9pondre \u00e0 toutes les questions et fournir des conseils sur la fa\u00e7on de d\u00e9panner et de r\u00e9soudre le probl\u00e8me.<\/p>\n<p>En r\u00e9sum\u00e9, notre processus de contr\u00f4le de qualit\u00e9 strict garantit que notre r\u00e9sine \u00e9poxy est de la plus haute qualit\u00e9 et que vous pouvez \u00eatre s\u00fbr qu&rsquo;elle fournira les meilleurs r\u00e9sultats. Et en cas de probl\u00e8me, il est tr\u00e8s probablement caus\u00e9 par l&rsquo;utilisateur final plut\u00f4t que par notre produit.<\/p>\n<p>En conclusion, notre processus de contr\u00f4le de qualit\u00e9 strict garantit que notre r\u00e9sine \u00e9poxy est de la plus haute qualit\u00e9 et que vous pouvez \u00eatre s\u00fbr qu&rsquo;elle fournira les meilleurs r\u00e9sultats. Nous prenons grand soin de nous approvisionner uniquement en mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9 et de tester chaque lot de r\u00e9sine \u00e9poxy pour en v\u00e9rifier la coh\u00e9rence et les performances. Nous comprenons que parfois, malgr\u00e9 tous nos efforts, nos clients peuvent rencontrer des probl\u00e8mes avec notre r\u00e9sine \u00e9poxy. Cependant, nous voulons nous assurer que la plupart des mauvais r\u00e9sultats sont caus\u00e9s par les utilisateurs finaux, tels qu&rsquo;un m\u00e9lange incorrect, une humidit\u00e9 \u00e9lev\u00e9e ou des temp\u00e9ratures \u00e9lev\u00e9es qui affectent le processus de durcissement et provoquent un durcissement incorrect de l&rsquo;\u00e9poxy. Nous recommandons toujours \u00e0 nos clients de lire attentivement et de suivre les instructions et les directives du fabricant pour de meilleurs r\u00e9sultats, et en cas de probl\u00e8me, nous sommes toujours disponibles pour r\u00e9pondre \u00e0 toutes les questions et fournir des conseils sur la fa\u00e7on de d\u00e9panner et de r\u00e9soudre le probl\u00e8me.<\/p>\n<p>LA DISCIPLINE EST LE CARBURANT DE LA R\u00c9USSITE\u2026<a href=\"https:\/\/www.polymerestechnologies.com\/\">POLYMERES TECHNOLOGIES<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9sine \u00e9poxy molle et collante : causes et solutions La r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9, une humidit\u00e9 \u00e9lev\u00e9e et des temp\u00e9ratures \u00e9lev\u00e9es. Une fois le temps de durcissement pass\u00e9, si vous constatez que votre r\u00e9sine reste collante, il est tr\u00e8s probable que vous n&rsquo;ayez pas [&#8230;]\n","protected":false},"author":1,"featured_media":16818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[444,447],"tags":[569,487,1255,699,677,682,461,1254,547,701,692,488],"class_list":["post-15574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faq-fr","category-troubleshooting-fr","tag-conseils-epoxy","tag-coulee-depoxy","tag-depannage-de-resine","tag-depannage-epoxy","tag-epoxy-uv-fr","tag-processus-de-durcissement-epoxy","tag-resine-claire","tag-resine-collante-fr","tag-resines-de-coulee","tag-taches-collantes-epoxy","tag-temps-de-durcissement-de-lepoxy","tag-top-coat-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9sine \u00e9poxy molle et collante : causes et solutions<\/title>\n<meta name=\"description\" content=\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions. Une r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions. Une r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/\" \/>\n<meta property=\"og:site_name\" content=\"CHILL EPOXY\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polymerestechnologies\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-06T17:46:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-07T18:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jsroch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"jsroch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/\"},\"author\":{\"name\":\"jsroch\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#\\\/schema\\\/person\\\/b0424518212430c1767885e3f3cf1d45\"},\"headline\":\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions\",\"datePublished\":\"2022-01-06T17:46:13+00:00\",\"dateModified\":\"2023-03-07T18:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/\"},\"wordCount\":1895,\"publisher\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chillepoxy.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Untitled-design.jpg\",\"keywords\":[\"conseils \u00e9poxy\",\"coul\u00e9e d'\u00e9poxy\",\"d\u00e9pannage de r\u00e9sine\",\"d\u00e9pannage \u00e9poxy\",\"\u00e9poxy uv\",\"processus de durcissement \u00e9poxy\",\"r\u00e9sine claire\",\"r\u00e9sine collante\",\"r\u00e9sines de coul\u00e9e\",\"taches collantes \u00e9poxy\",\"temps de durcissement de l'\u00e9poxy\",\"top coat\"],\"articleSection\":[\"FAQ\",\"Troubleshooting\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/\",\"url\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/\",\"name\":\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chillepoxy.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Untitled-design.jpg\",\"datePublished\":\"2022-01-06T17:46:13+00:00\",\"dateModified\":\"2023-03-07T18:55:29+00:00\",\"description\":\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions. Une r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chillepoxy.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Untitled-design.jpg\",\"contentUrl\":\"https:\\\/\\\/chillepoxy.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Untitled-design.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Soft or Sticky Epoxy - Resin troubleshooting\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sine \u00e9poxy molle et collante : causes et solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/\",\"name\":\"CHILL EPOXY\u2122 High-Quality Canadian-Made Epoxy Resin\",\"description\":\"High-Quality Canadian-Made Epoxy Resin | Casting &amp; Art\",\"publisher\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#organization\"},\"alternateName\":\"High-Quality Epoxy Resin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#organization\",\"name\":\"CHILL EPOXY\u2122\",\"alternateName\":\"High-Quality Canadian-Made Epoxy Resin\",\"url\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/chillepoxy.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/polymeres_technologies.png?fit=649%2C649&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/chillepoxy.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/polymeres_technologies.png?fit=649%2C649&ssl=1\",\"width\":649,\"height\":649,\"caption\":\"CHILL EPOXY\u2122\"},\"image\":{\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/polymerestechnologies\\\/\",\"https:\\\/\\\/www.instagram.com\\\/polymeres_technologies\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/polymeres-technologies\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDaFKmK4Hn3KPKmBaTXWong\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chillepoxy.com\\\/fr\\\/#\\\/schema\\\/person\\\/b0424518212430c1767885e3f3cf1d45\",\"name\":\"jsroch\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions","description":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions. Une r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions","og_description":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions. Une r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9.","og_url":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/","og_site_name":"CHILL EPOXY","article_publisher":"https:\/\/www.facebook.com\/polymerestechnologies\/","article_published_time":"2022-01-06T17:46:13+00:00","article_modified_time":"2023-03-07T18:55:29+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg","type":"image\/jpeg"}],"author":"jsroch","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"jsroch","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#article","isPartOf":{"@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/"},"author":{"name":"jsroch","@id":"https:\/\/chillepoxy.com\/fr\/#\/schema\/person\/b0424518212430c1767885e3f3cf1d45"},"headline":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions","datePublished":"2022-01-06T17:46:13+00:00","dateModified":"2023-03-07T18:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/"},"wordCount":1895,"publisher":{"@id":"https:\/\/chillepoxy.com\/fr\/#organization"},"image":{"@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#primaryimage"},"thumbnailUrl":"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg","keywords":["conseils \u00e9poxy","coul\u00e9e d'\u00e9poxy","d\u00e9pannage de r\u00e9sine","d\u00e9pannage \u00e9poxy","\u00e9poxy uv","processus de durcissement \u00e9poxy","r\u00e9sine claire","r\u00e9sine collante","r\u00e9sines de coul\u00e9e","taches collantes \u00e9poxy","temps de durcissement de l'\u00e9poxy","top coat"],"articleSection":["FAQ","Troubleshooting"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/","url":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/","name":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions","isPartOf":{"@id":"https:\/\/chillepoxy.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#primaryimage"},"image":{"@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#primaryimage"},"thumbnailUrl":"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg","datePublished":"2022-01-06T17:46:13+00:00","dateModified":"2023-03-07T18:55:29+00:00","description":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions. Une r\u00e9sine \u00e9poxy molle ou collante peut \u00eatre caus\u00e9e par divers probl\u00e8mes, notamment un m\u00e9lange inappropri\u00e9.","breadcrumb":{"@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#primaryimage","url":"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg","contentUrl":"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg","width":1920,"height":1920,"caption":"Soft or Sticky Epoxy - Resin troubleshooting"},{"@type":"BreadcrumbList","@id":"https:\/\/chillepoxy.com\/fr\/taches-depoxy-collante-ou-couche-de-resine-collante-pourquoi-ma-couche-de-resine-est-elle-encore-collante-a-certains-endroits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chillepoxy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sine \u00e9poxy molle et collante : causes et solutions"}]},{"@type":"WebSite","@id":"https:\/\/chillepoxy.com\/fr\/#website","url":"https:\/\/chillepoxy.com\/fr\/","name":"CHILL EPOXY\u2122 High-Quality Canadian-Made Epoxy Resin","description":"High-Quality Canadian-Made Epoxy Resin | Casting &amp; Art","publisher":{"@id":"https:\/\/chillepoxy.com\/fr\/#organization"},"alternateName":"High-Quality Epoxy Resin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chillepoxy.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chillepoxy.com\/fr\/#organization","name":"CHILL EPOXY\u2122","alternateName":"High-Quality Canadian-Made Epoxy Resin","url":"https:\/\/chillepoxy.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chillepoxy.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/chillepoxy.com\/wp-content\/uploads\/2024\/02\/polymeres_technologies.png?fit=649%2C649&ssl=1","contentUrl":"https:\/\/i0.wp.com\/chillepoxy.com\/wp-content\/uploads\/2024\/02\/polymeres_technologies.png?fit=649%2C649&ssl=1","width":649,"height":649,"caption":"CHILL EPOXY\u2122"},"image":{"@id":"https:\/\/chillepoxy.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/polymerestechnologies\/","https:\/\/www.instagram.com\/polymeres_technologies\/","https:\/\/www.linkedin.com\/company\/polymeres-technologies\/","https:\/\/www.youtube.com\/channel\/UCDaFKmK4Hn3KPKmBaTXWong"]},{"@type":"Person","@id":"https:\/\/chillepoxy.com\/fr\/#\/schema\/person\/b0424518212430c1767885e3f3cf1d45","name":"jsroch"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/chillepoxy.com\/wp-content\/uploads\/2021\/11\/Untitled-design.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/posts\/15574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/comments?post=15574"}],"version-history":[{"count":0,"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/posts\/15574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/media\/16818"}],"wp:attachment":[{"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/media?parent=15574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/categories?post=15574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chillepoxy.com\/fr\/wp-json\/wp\/v2\/tags?post=15574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}